{"id":5697,"date":"2025-05-22T13:17:22","date_gmt":"2025-05-22T13:17:22","guid":{"rendered":"https:\/\/voxtours.com\/soluzioni-di-traduzione-live-basate-sullia\/"},"modified":"2026-07-03T07:32:41","modified_gmt":"2026-07-03T07:32:41","slug":"vox-aura","status":"publish","type":"page","link":"https:\/\/voxtours.com\/it\/vox-aura\/","title":{"rendered":"Vox Aura"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5697\" class=\"elementor elementor-5697 elementor-1734\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d122a1d e-flex e-con-boxed e-con e-parent\" data-id=\"d122a1d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23bfc51 elementor-widget elementor-widget-image\" data-id=\"23bfc51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"720\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2026\/06\/top-aura-banner-v2.jpg\" class=\"attachment-full size-full wp-image-6599\" alt=\"Vox Aura - The AI smart Transmitter\" srcset=\"https:\/\/voxtours.com\/wp-content\/uploads\/2026\/06\/top-aura-banner-v2.jpg 1920w, https:\/\/voxtours.com\/wp-content\/uploads\/2026\/06\/top-aura-banner-v2-300x113.jpg 300w, https:\/\/voxtours.com\/wp-content\/uploads\/2026\/06\/top-aura-banner-v2-1024x384.jpg 1024w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f3ff20 e-flex e-con-boxed e-con e-parent\" data-id=\"9f3ff20\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bea1a77 elementor-widget elementor-widget-heading\" data-id=\"bea1a77\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:1}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#0170A5\">Vox Aura<\/span> - Ridefinire il futuro dell'esperienza di viaggio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32f5776 e-grid e-con-boxed e-con e-parent\" data-id=\"32f5776\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-33f2da5 e-con-full e-flex e-con e-child\" data-id=\"33f2da5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4136842 e-con-full elementor-hidden-desktop elementor-hidden-tablet e-flex e-con e-child\" data-id=\"4136842\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36db960 elementor-widget elementor-widget-image\" data-id=\"36db960\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"828\" height=\"720\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2025\/05\/Vox-connect-v2-1.jpg\" class=\"attachment-full size-full wp-image-5613\" alt=\"Vox Connect AI\" srcset=\"https:\/\/voxtours.com\/wp-content\/uploads\/2025\/05\/Vox-connect-v2-1.jpg 828w, https:\/\/voxtours.com\/wp-content\/uploads\/2025\/05\/Vox-connect-v2-1-300x261.jpg 300w\" sizes=\"(max-width: 828px) 100vw, 828px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fca3903 elementor-widget elementor-widget-heading\" data-id=\"fca3903\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vox <span style=\"color:#0170A5\">Aura<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-606d71d elementor-widget elementor-widget-text-editor\" data-id=\"606d71d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per la prima volta, un intero gruppo, di qualsiasi dimensione, pu\u00f2 seguire la propria guida nella propria lingua, in simultanea, in tempo reale. Nessuno smartphone. Nessuna app. Nessun costo di roaming. Nessun interprete.<\/p><p>Ma Vox Aura non \u00e8 solo un dispositivo di traduzione simultanea.<\/p><p>Aura \u00e8 uno smart transmitter costruito per tour leader, guide e direttori di crociera. Il suo funzionamento di base \u00e8 come le radio Vox di cui le vostre guide si fidano da 25 anni: stessa qualit\u00e0 audio, stessa portata, stessa affidabilit\u00e0. Ci\u00f2 che \u00e8 nuovo \u00e8 la sua tecnologia e le sue potenzialit\u00e0.<\/p><p>La guida parla una volta. Aura trasmette il commento in diretta, in fino a quattro lingue contemporaneamente, scelte da una libreria di 200 lingue. E non si limita a tradurre: si adatta. Lo stesso tour pu\u00f2 essere modellato diversamente per una famiglia, un gruppo di specialisti o un visitatore alla prima visita, ciascuno sul proprio canale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec2076c e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"ec2076c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f596900 elementor-widget elementor-widget-image\" data-id=\"f596900\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1077\" height=\"1079\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2026\/02\/Vox-Aura-2025-new-version.jpg\" class=\"attachment-full size-full wp-image-6516\" alt=\"Vox Aura - New AI powered multilingual live translation device\" srcset=\"https:\/\/voxtours.com\/wp-content\/uploads\/2026\/02\/Vox-Aura-2025-new-version.jpg 1077w, https:\/\/voxtours.com\/wp-content\/uploads\/2026\/02\/Vox-Aura-2025-new-version-300x300.jpg 300w, https:\/\/voxtours.com\/wp-content\/uploads\/2026\/02\/Vox-Aura-2025-new-version-1022x1024.jpg 1022w, https:\/\/voxtours.com\/wp-content\/uploads\/2026\/02\/Vox-Aura-2025-new-version-150x150.jpg 150w, https:\/\/voxtours.com\/wp-content\/uploads\/2026\/02\/Vox-Aura-2025-new-version-700x700.jpg 700w\" sizes=\"(max-width: 1077px) 100vw, 1077px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a111f11 e-flex e-con-boxed e-con e-parent\" data-id=\"a111f11\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-536107f elementor-widget elementor-widget-text-editor\" data-id=\"536107f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aura funziona come un co-pilota intelligente per tutta la durata del tour: ascolta, suggerisce informazioni verificate quando un ospite pone una domanda inattesa, e supporta ogni guida nell&#8217;offrire un&#8217;esperienza di alto livello, indipendentemente dalla sua esperienza. Se il tour subisce un ritardo, la guida pu\u00f2 improvvisare una storia o un quiz culturale al momento, mantenendo il gruppo coinvolto<\/p><p>Nessuna rete? Aura continua a funzionare, trasmettendo contenuti multilingue precaricati direttamente dal dispositivo. Per gli ospiti con problemi di udito, invia sottotitoli in tempo reale sullo smartphone, senza attrezzature aggiuntive, senza esclusioni.<\/p><p>La domanda non \u00e8 pi\u00f9 se il tuo gruppo pu\u00f2 capire la guida. \u00c8 se la tua guida ha gli strumenti per offrire a ogni ospite un&#8217;esperienza diversa, ogni volta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9cc1e5 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"f9cc1e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#get-in-touch\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contattaci<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f73bf58 e-flex e-con-boxed e-con e-parent\" data-id=\"f73bf58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74e670a elementor-widget elementor-widget-video\" data-id=\"74e670a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=6kYbyG_9YWA&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a77d1f1 e-flex e-con-boxed e-con e-parent\" data-id=\"a77d1f1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19feaa8 elementor-widget elementor-widget-heading\" data-id=\"19feaa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contattaci<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a379ba elementor-widget elementor-widget-text-editor\" data-id=\"4a379ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/embed\/v2.js\"><\/script>\n<script>\n  hbspt.forms.create({\n    portalId: \"3908093\",\n    formId: \"31c7ecf8-cb35-494a-a6a8-6da28e6f7668\",\n    region: \"na1\"\n  });\n<\/script>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3df6748 e-flex e-con-boxed e-con e-parent\" data-id=\"3df6748\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-55056e6 e-con-full e-flex e-con e-child\" data-id=\"55056e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8aa9dbc elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"8aa9dbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#008EC8\">Soluzioni <\/span>per ogni settore<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-313a5fd elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"313a5fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In un settore dei viaggi in rapida evoluzione, Vox \u00e8 un faro di progresso che guida la rivitalizzazione del settore. Promuovendo l&#8217;innovazione, permettiamo ai nostri partner di ottenere prestazioni superiori attraverso le nostre soluzioni di autoguida e guida di gruppo. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c4915e sector-inner-rw e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"4c4915e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b81c7a sector_carosal  nw-sctr-sldr elementor-widget elementor-widget-ucaddon_card_carousel\" data-id=\"9b81c7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_card_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Card Carousel -->\n\t\t<link id='font-awesome-css' href='https:\/\/voxtours.com\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/voxtours.com\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='owl-carousel-css' href='https:\/\/voxtours.com\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/owl-carousel-new\/assets\/owl.carousel.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='uc_ac_assets_file_animate_css_77907-css' href='https:\/\/voxtours.com\/wp-content\/uploads\/ac_assets\/uc_classic_carousel\/animate.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Card Carousel *\/\n\n#uc_card_carousel_elementor_9b81c7a-wrapper{\n  min-height:1px;\n}\n\n#uc_card_carousel_elementor_9b81c7a *{\n\t-webkit-box-sizing: border-box;\n\t-moz-box-sizing: border-box;\n\tbox-sizing: border-box;\n}\n\n#uc_card_carousel_elementor_9b81c7a .ue-carousel-item{\n  overflow:hidden;\n  transition:0.3s;\n}\n\n#uc_card_carousel_elementor_9b81c7a .uc_classic_carousel_container_holder{\n\tdisplay:block;\n\tposition:relative;\n\twidth:100%;\n    box-sizing: border-box;\n}\n#uc_card_carousel_elementor_9b81c7a .uc_classic_carousel_placeholder{\n   position:relative;\n}\n\n\n#uc_card_carousel_elementor_9b81c7a .uc_classic_carousel_placeholder img, #uc_card_carousel_elementor_9b81c7a .ue_card_carousel_image_overlay{\n  transition: all 300ms;\n}\n\n.card_carousel_title{\n\tfont-size:21px;\n}\n\n.uc_classic_carousel .uc_classic_carousel_border{\n\tdisplay:block;\n    margin:0 auto;\n}\n\n.uc_classic_carousel  .uc_classic_carousel_placeholder img{\n\twidth:100%;    \n    display:inline-flex;\n}\n\n.uc_classic_carousel .uc_classic_carousel_content{\n  display: flex;\n  flex-flow: column nowrap;\n}\n\n.uc_classic_carousel .ue_button{\n  margin-top:auto;\n}\n\n.uc_classic_carousel .uc_classic_carousel_content .uc_more_btn {\n\tdisplay:inline-block;\n\ttext-decoration:none;\n\ttransition: all 0.5s ease;\n}\n\n#uc_card_carousel_elementor_9b81c7a .owl-dots {\n  overflow:hidden;\n  text-align:center;\n}\n\n#uc_card_carousel_elementor_9b81c7a .owl-dot {\n  border-radius:50%;\n  display:inline-block;\n}\n\n#uc_card_carousel_elementor_9b81c7a .owl-nav .owl-prev,\n#uc_card_carousel_elementor_9b81c7a .owl-nav .owl-next{\n    position:absolute;\n    display:flex;\n  \tjustify-content: center;\n  \talign-items: center;\n    text-align:center;\n}\n\n#uc_card_carousel_elementor_9b81c7a .owl-nav .disabled{\n    display: none;  \n}\n\n\n#uc_card_carousel_elementor_9b81c7a .ue-item-icon{\n  line-height:1em;\n  display:inline-flex;\n  justify-content:center;\n  align-items:center;  \n}\n\n#uc_card_carousel_elementor_9b81c7a .ue-item-icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_card_carousel_elementor_9b81c7a .ue-item-icon-wrapper{\n  display:flex;\n}\n\n#uc_card_carousel_elementor_9b81c7a .uc_classic_carousel_container_holder {\n\t max-width: ;\n}\n\n\n\n@media screen and (max-width: 1024px) {\n  #uc_card_carousel_elementor_9b81c7a .uc_classic_carousel_container_holder {\n\t max-width: ;\n  }\n}\n\n@media screen and (max-width: 767px) {\n  #uc_card_carousel_elementor_9b81c7a .uc_classic_carousel_container_holder {\n    max-width: ;\n  }\n}\n\n<\/style>\n\n<div class=\"uc_classic_carousel\" id=\"uc_card_carousel_elementor_9b81c7a-wrapper\">\n        <div class=\"uc_carousel owl-carousel uc-items-wrapper  \" id=\"uc_card_carousel_elementor_9b81c7a\"  >\n          \t\n\n\n<div id=\"uc_card_carousel_elementor_9b81c7a_item1\" class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-05ebdb9\" data-hide-item=\"false\">  \n  <div class=\"ue-carousel-item\">\n    \n    <span class=\"uc_classic_carousel_border\" style=\"\"><\/span>    \n    \n          <div class=\"uc_classic_carousel_placeholder\">\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/09\/Touring.jpg\"  src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/09\/Touring.jpg\" alt=\"Touring\" width=\"765\" height=\"765\">\n                      <\/div>\n    \n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">    \n\n      \n          <div  class=\"card_carousel_title\"><span class=\"notranslate\">Touring<\/span><\/div>\n        <p class=\"card_carousel_text\"><span class=\"notranslate\">Semplifica le operazioni e migliora i tour di gruppo con i nostri sistemi di guida, tecnologia multilingue e supporto logistico per esperienze impeccabili.<\/span><\/p>      \t\n\n              <div class=\"ue_button\">\n          <a class=\"uc_more_btn \" href=\"\/case-studies\/\" title=\"\" ><\/a>\n      \t<\/div>   \n      \t\n      \n    <\/div>\n    \n  <\/div>\n<\/div>\n\n\n\n<div id=\"uc_card_carousel_elementor_9b81c7a_item2\" class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-de34a54\" data-hide-item=\"false\">  \n  <div class=\"ue-carousel-item\">\n    \n    <span class=\"uc_classic_carousel_border\" style=\"\"><\/span>    \n    \n          <div class=\"uc_classic_carousel_placeholder\">\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/09\/Cruising.jpg\"  src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/09\/Cruising.jpg\" alt=\"Cruising\" width=\"800\" height=\"533\">\n                      <\/div>\n    \n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">    \n\n      \n          <div  class=\"card_carousel_title\">Crociere<\/div>\n        <p class=\"card_carousel_text\">Arricchisci le escursioni a terra con sistemi di guida, contenuti multilingue e logistica senza intoppi, garantendo esperienze di viaggio eccezionali.<\/p>      \t\n\n              <div class=\"ue_button\">\n          <a class=\"uc_more_btn \" href=\"\/case-studies\/\" title=\"\" ><\/a>\n      \t<\/div>   \n      \t\n      \n    <\/div>\n    \n  <\/div>\n<\/div>\n\n\n\n<div id=\"uc_card_carousel_elementor_9b81c7a_item3\" class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-153d44a\" data-hide-item=\"false\">  \n  <div class=\"ue-carousel-item\">\n    \n    <span class=\"uc_classic_carousel_border\" style=\"\"><\/span>    \n    \n          <div class=\"uc_classic_carousel_placeholder\">\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2026\/06\/Sightseeing.jpg\"  src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2026\/06\/Sightseeing.jpg\" alt=\"Sightseeing\" width=\"840\" height=\"560\">\n                      <\/div>\n    \n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">    \n\n      \n          <div  class=\"card_carousel_title\">Visite turistiche<\/div>\n        <p class=\"card_carousel_text\">Migliora i tour cittadini con sistemi di guida all'avanguardia, contenuti multilingue e mappe interattive per un'esperienza coinvolgente per i visitatori.<\/p>      \t\n\n              <div class=\"ue_button\">\n          <a class=\"uc_more_btn \" href=\"\/case-studies\/\" title=\"\" ><\/a>\n      \t<\/div>   \n      \t\n      \n    <\/div>\n    \n  <\/div>\n<\/div>\n\n\n\n<div id=\"uc_card_carousel_elementor_9b81c7a_item4\" class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-3041dc6\" data-hide-item=\"false\">  \n  <div class=\"ue-carousel-item\">\n    \n    <span class=\"uc_classic_carousel_border\" style=\"\"><\/span>    \n    \n          <div class=\"uc_classic_carousel_placeholder\">\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/08\/Promo_3.png\"  src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/08\/Promo_3.png\" alt=\"Promo_3\" width=\"382\" height=\"446\">\n                      <\/div>\n    \n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">    \n\n      \n          <div  class=\"card_carousel_title\"><span class=\"notranslate\">Hop-on hop-off<\/span><\/div>\n        <p class=\"card_carousel_text\"><span class=\"notranslate\">Ottimizza i tour con soluzioni digitali, tracciamento in tempo reale e guide audio multilingue per viaggi fluidi e piacevoli.<\/span><\/p>      \t\n\n              <div class=\"ue_button\">\n          <a class=\"uc_more_btn \" href=\"\/case-studies\/\" title=\"\" ><\/a>\n      \t<\/div>   \n      \t\n      \n    <\/div>\n    \n  <\/div>\n<\/div>\n\n\n\n<div id=\"uc_card_carousel_elementor_9b81c7a_item5\" class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-39d2671\" data-hide-item=\"false\">  \n  <div class=\"ue-carousel-item\">\n    \n    <span class=\"uc_classic_carousel_border\" style=\"\"><\/span>    \n    \n          <div class=\"uc_classic_carousel_placeholder\">\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/08\/Promo_1.png\"  src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/08\/Promo_1.png\" alt=\"Promo_1\" width=\"381\" height=\"446\">\n                      <\/div>\n    \n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">    \n\n      \n          <div  class=\"card_carousel_title\">OTA<\/div>\n        <p class=\"card_carousel_text\">Arricchisci biglietti ed esperienze con le nostre guide di viaggio multilingue e itinerari personalizzati per aggiungere valore e differenziare le tue offerte.<\/p>      \t\n\n              <div class=\"ue_button\">\n          <a class=\"uc_more_btn \" href=\"\/case-studies\/\" title=\"\" ><\/a>\n      \t<\/div>   \n      \t\n      \n    <\/div>\n    \n  <\/div>\n<\/div>\n\n\n\n<div id=\"uc_card_carousel_elementor_9b81c7a_item6\" class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-ec193b9\" data-hide-item=\"false\">  \n  <div class=\"ue-carousel-item\">\n    \n    <span class=\"uc_classic_carousel_border\" style=\"\"><\/span>    \n    \n          <div class=\"uc_classic_carousel_placeholder\">\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/08\/Promo_5.png\"  src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/08\/Promo_5.png\" alt=\"Promo_5\" width=\"382\" height=\"446\">\n                      <\/div>\n    \n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">    \n\n      \n          <div  class=\"card_carousel_title\">Luoghi\/musei<\/div>\n        <p class=\"card_carousel_text\">Migliora le esperienze dei visitatori con dispositivi di autoguida, mostre interattive e contenuti multilingue per un pubblico diversificato.<\/p>      \t\n\n              <div class=\"ue_button\">\n          <a class=\"uc_more_btn \" href=\"\/case-studies\/\" title=\"\" ><\/a>\n      \t<\/div>   \n      \t\n      \n    <\/div>\n    \n  <\/div>\n<\/div>\n\n\n\n<div id=\"uc_card_carousel_elementor_9b81c7a_item7\" class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-41b65b7\" data-hide-item=\"false\">  \n  <div class=\"ue-carousel-item\">\n    \n    <span class=\"uc_classic_carousel_border\" style=\"\"><\/span>    \n    \n          <div class=\"uc_classic_carousel_placeholder\">\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/09\/DMOs.jpg\"  src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/09\/DMOs.jpg\" alt=\"DMOs\" width=\"559\" height=\"370\">\n                      <\/div>\n    \n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">    \n\n      \n          <div  class=\"card_carousel_title\">Citt\u00e0 e DMO<\/div>\n        <p class=\"card_carousel_text\">Dai una spinta al turismo con soluzioni di pass digitali, analisi dei dati e piattaforme di gestione turistica su misura per ambienti urbani.<\/p>      \t\n\n              <div class=\"ue_button\">\n          <a class=\"uc_more_btn \" href=\"\/solutions\/\" title=\"\" ><\/a>\n      \t<\/div>   \n      \t\n      \n    <\/div>\n    \n  <\/div>\n<\/div>\n\n\n\n<div id=\"uc_card_carousel_elementor_9b81c7a_item8\" class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-2b418b5\" data-hide-item=\"false\">  \n  <div class=\"ue-carousel-item\">\n    \n    <span class=\"uc_classic_carousel_border\" style=\"\"><\/span>    \n    \n          <div class=\"uc_classic_carousel_placeholder\">\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/09\/Mobility-Providers.jpg\"  src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/09\/Mobility-Providers.jpg\" alt=\"Mobility Providers\" width=\"880\" height=\"587\">\n                      <\/div>\n    \n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">    \n\n      \n          <div  class=\"card_carousel_title\">Fornitori di mobilit\u00e0<\/div>\n        <p class=\"card_carousel_text\">Integra la nostra tecnologia per un accesso comodo ai trasporti, navigazione in tempo reale, commenti multilingue e guide personalizzate.<\/p>      \t\n\n              <div class=\"ue_button\">\n          <a class=\"uc_more_btn \" href=\"\/case-studies\/\" title=\"\" ><\/a>\n      \t<\/div>   \n      \t\n      \n    <\/div>\n    \n  <\/div>\n<\/div>\n\n\n\n<div id=\"uc_card_carousel_elementor_9b81c7a_item9\" class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-139eca8\" data-hide-item=\"false\">  \n  <div class=\"ue-carousel-item\">\n    \n    <span class=\"uc_classic_carousel_border\" style=\"\"><\/span>    \n    \n          <div class=\"uc_classic_carousel_placeholder\">\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/09\/Self-drive.jpg\"  src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/09\/Self-drive.jpg\" alt=\"Self drive\" width=\"780\" height=\"520\">\n                      <\/div>\n    \n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">    \n\n      \n          <div  class=\"card_carousel_title\"><span class=\"notranslate\">Guida autonoma<\/span><\/div>\n        <p class=\"card_carousel_text\"><span class=\"notranslate\">Potenzia i tour self-drive con mappe interattive e guide audio multilingue per un'esplorazione flessibile e autonoma.<\/span><\/p>      \t\n\n              <div class=\"ue_button\">\n          <a class=\"uc_more_btn \" href=\"\/case-studies\/\" title=\"\" ><\/a>\n      \t<\/div>   \n      \t\n      \n    <\/div>\n    \n  <\/div>\n<\/div>\n\n\n\n<div id=\"uc_card_carousel_elementor_9b81c7a_item10\" class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-c93098f\" data-hide-item=\"false\">  \n  <div class=\"ue-carousel-item\">\n    \n    <span class=\"uc_classic_carousel_border\" style=\"\"><\/span>    \n    \n          <div class=\"uc_classic_carousel_placeholder\">\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/09\/MICE.jpg\"  src=\"https:\/\/voxtours.com\/wp-content\/uploads\/2024\/09\/MICE.jpg\" alt=\"MICE\" width=\"559\" height=\"373\">\n                      <\/div>\n    \n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">    \n\n      \n          <div  class=\"card_carousel_title\"><span class=\"notranslate\">MICE<\/span><\/div>\n        <p class=\"card_carousel_text\"><span class=\"notranslate\">Offri trasmissioni audio e multilingue impeccabili con radio digitali e connettiti con i delegati attraverso la nostra tecnologia di mappatura e guida.<\/span><\/p>      \t\n\n              <div class=\"ue_button\">\n          <a class=\"uc_more_btn \" href=\"\/case-studies\/\" title=\"\" ><\/a>\n      \t<\/div>   \n      \t\n      \n    <\/div>\n    \n  <\/div>\n<\/div>\n\n      <\/div>\n<\/div>\n<!-- end Card Carousel -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9586aad elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9586aad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/voxtours.com\/contact-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contattaci<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vox Aura &#8211; Ridefinire il futuro dell&#8217;esperienza di viaggio Vox Aura Per la prima volta, un intero gruppo, di qualsiasi dimensione, pu\u00f2 seguire la propria guida nella propria lingua, in simultanea, in tempo reale. Nessuno smartphone. Nessuna app. Nessun costo di roaming. Nessun interprete. Ma Vox Aura non \u00e8 solo un dispositivo di traduzione simultanea&#8230;.<\/p>\n","protected":false},"author":14,"featured_media":6677,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5697","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/voxtours.com\/it\/wp-json\/wp\/v2\/pages\/5697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voxtours.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/voxtours.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/voxtours.com\/it\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/voxtours.com\/it\/wp-json\/wp\/v2\/comments?post=5697"}],"version-history":[{"count":0,"href":"https:\/\/voxtours.com\/it\/wp-json\/wp\/v2\/pages\/5697\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voxtours.com\/it\/wp-json\/wp\/v2\/media\/6677"}],"wp:attachment":[{"href":"https:\/\/voxtours.com\/it\/wp-json\/wp\/v2\/media?parent=5697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}